{"id":30443,"date":"2026-01-31T15:32:20","date_gmt":"2026-01-31T14:32:20","guid":{"rendered":"https:\/\/tienda.anclademia.com\/?post_type=product&#038;p=30443"},"modified":"2026-03-24T15:08:51","modified_gmt":"2026-03-24T14:08:51","slug":"transizione-da-pnb-a-per","status":"publish","type":"product","link":"https:\/\/tienda.anclademia.com\/it\/product\/transizione-da-pnb-a-per\/","title":{"rendered":"Corso di transizione da PNB a PER"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"30443\" class=\"elementor elementor-30443\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-7fb6dcd wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"7fb6dcd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d34368 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"3d34368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-large text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h1 class=\"woodmart-title-container title wd-fontsize-xxl\">Dal PIL al PER<\/h1> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-538474a elementor-widget elementor-widget-wd_text_block\" data-id=\"538474a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-center\">\n\t\t\t\n\t\t\t<h2><b>Passaggio da PNB a PER \u2014 Registrazione online<\/b><\/h2><p class=\"p3\">Se hai gi\u00e0 il titolo di <span class=\"s2\"><b>Schema di navigazione di base (BNP)<\/b><\/span>, puoi ottenere il <span class=\"s2\"><b>Conduttore di imbarcazioni da diporto (PER)<\/b><\/span> pi\u00f9 rapidamente ed efficacemente, poich\u00e9 <span class=\"s2\"><b>convalida parte della teoria<\/b><\/span> del programma di base. Ci\u00f2 significa che dovrai solo preparare i moduli avanzati del PER e completare il <span class=\"s2\"><b>completare i tirocini obbligatori<\/b><\/span>, come richiesto dalle normative ufficiali.<\/p><p class=\"p3\">Con questa iscrizione ti assicurerai l&#039;accesso al corso a tariffa ridotta, riceverai supporto personalizzato e potrai progredire verso una qualifica che amplier\u00e0 significativamente le tue competenze nautiche.<\/p><h2><b>Cosa \u00e8 incluso nell&#039;acquisto<\/b><\/h2><p class=\"p3\">Con questa registrazione otterrai:<\/p><ul><li><p class=\"p1\" style=\"text-align: left;\"><span class=\"s1\"><b>Teoria ridotta<\/b><\/span> focalizzato esclusivamente su contenuti NON convalidati dal PNB.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\"><span class=\"s1\"><b>Accesso ai materiali ufficiali PER<\/b><\/span>Programma online, esercizi, grafici, problemi di navigazione e test.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\"><b>16 ore di formazione su sicurezza e navigazione (obbligatorie)<\/b><span class=\"s1\">.<\/span><\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\"><b>12 ore di formazione pratica ROCA<\/b><span class=\"s1\"> (se non li avete gi\u00e0).<\/span><\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\"><span class=\"s1\"><b>Supporto personalizzato<\/b><\/span> per aiutarti a prepararti per l&#039;esame PER ufficiale.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\"><span class=\"s1\"><b>Gestione amministrativa<\/b><\/span> per iscriversi all&#039;esame e completare le pratiche per il conseguimento del titolo di studio finale.<\/p><\/li><\/ul><p class=\"p3\"><i>Importante<\/i>Sebbene parte della teoria sia convalidata, <span class=\"s2\"><b>I corsi di formazione obbligatori per il PER (Recreational Skipper&#039;s License) non sono convalidati.<\/b><\/span> e deve essere eseguita integralmente.<\/p><h2><b>Convalide da PNB<\/b><\/h2><p class=\"p3\">In qualit\u00e0 di studente in possesso di una qualifica PNB:<\/p><h3><b>\u2714\ufe0f <\/b><\/h3><h3><b>\u00c8 stato convalidato:<\/b><\/h3><ul><li><p class=\"p1\" style=\"text-align: left;\">Parte del programma teorico di base condiviso tra PNB e PER.<\/p><\/li><\/ul><h3><b>\u274c <\/b><\/h3><h3><b>NON convalidato:<\/b><\/h3><ul><li><p class=\"p1\" style=\"text-align: left;\">Pratiche di sicurezza e navigazione (16 ore)<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Esercitazioni pratiche di Radio ROCA (12 ore)<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Esame teorico PER completo ufficiale<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Pratica di vela facoltativa<\/p><\/li><li><p class=\"p1\" style=\"text-align: left;\">Estensione facoltativa per le esercitazioni di traversata fino a 24 metri verso le Isole Baleari.<\/p><\/li><\/ul><p class=\"p3\">Il regolamento richiede l&#039;esecuzione del <span class=\"s2\"><b>tutte le pratiche<\/b><\/span> del PER anche se hai gi\u00e0 il GNP.<\/p><h2><b>Autorizzazioni che otterrai passando a PER<\/b><\/h2><p class=\"p3\">Il PER offre vantaggi che superano il PIL:<\/p><ul><li><p class=\"p1\" style=\"text-align: left;\">Per comandare navi fino a <span class=\"s1\"><b>15 metri<\/b><\/span> in lunghezza (estensibile a <span class=\"s1\"><b>24 metri<\/b><\/span> con ulteriore pratica).<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Naviga verso <span class=\"s1\"><b>12 miglia<\/b><\/span> dalla costa.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Navigazione tra le isole dell&#039;arcipelago delle Baleari o delle Canarie.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Con estensione pratica: navigazione tra la penisola e le isole Baleari.<\/p><\/li><li><p class=\"p1\" style=\"text-align: left;\">Con la pratica della vela: qualificazione velica per tutti i titoli.<\/p><\/li><\/ul><h2><b>Come funziona il processo<\/b><\/h2><ol start=\"1\"><li><p class=\"p1\" style=\"text-align: left;\"><span class=\"s1\"><b>Acquista online<\/b><\/span> questa registrazione.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Ottieni l&#039;accesso al tuo <span class=\"s1\"><b>campus e materiale ridotto<\/b><\/span> per coloro che gi\u00e0 possiedono il PIL.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Completare il <span class=\"s1\"><b>teoria avanzata della PER<\/b><\/span> con il supporto dei nostri istruttori.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Eseguire il <span class=\"s1\"><b>pratiche obbligatorie<\/b><\/span> navigazione e radio.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Ti aiutiamo a iscriverti al <span class=\"s1\"><b>esame ufficiale<\/b><\/span> del PER.<\/p><\/li><li><p class=\"p1\" style=\"text-align: left;\">Dopo aver approvato e inviato la documentazione, gestiamo il <span class=\"s1\"><b>rilascio del titolo PER<\/b><\/span>.<\/p><\/li><\/ol><h2><b>Informazioni importanti<\/b><\/h2><ul><li><p class=\"p1\" style=\"text-align: left;\">\u00c8 obbligatorio fornire il <span class=\"s1\"><b>certificato medico<\/b><\/span> per il rilascio del PER.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">\u00c8 possibile esercitarsi prima o dopo l&#039;esame.<\/p><\/li><li style=\"text-align: left;\"><p class=\"p1\">Se desideri navigare a vela o passare a un&#039;imbarcazione di 24 metri, puoi aggiungere gli optional pratici.<\/p><\/li><li><p class=\"p1\" style=\"text-align: left;\">Le tasse d&#039;esame e le spese per il rilascio del diploma non sono incluse.<\/p><\/li><\/ul><h2><b>Link utili<\/b><\/h2><p class=\"p3\">Puoi scoprire di pi\u00f9 <a href=\"https:\/\/anclademia.com\/patron-de-embarcacion-de-recreo\/\" target=\"_blank\" rel=\"noopener\">Informazioni PER<\/a> sulla pagina informativa ufficiale della scuola.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Valorizza la tua qualifica PNB e passa alla PER convalidando parte del programma di studi. Include l&#039;accesso a specifiche lezioni teoriche, formazione pratica obbligatoria, materiali di studio e supporto fino all&#039;esame.<\/p>","protected":false},"featured_media":29763,"template":"","meta":[],"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":["post-30443","product","type-product","status-publish","has-post-thumbnail","product_cat-titulos-nauticos-de-recreo","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/product\/30443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":6,"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/product\/30443\/revisions"}],"predecessor-version":[{"id":30739,"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/product\/30443\/revisions\/30739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/media\/29763"}],"wp:attachment":[{"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/media?parent=30443"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/product_brand?post=30443"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/product_cat?post=30443"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tienda.anclademia.com\/it\/wp-json\/wp\/v2\/product_tag?post=30443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}